{"id":12169,"date":"2020-03-05T22:10:12","date_gmt":"2020-03-05T22:10:12","guid":{"rendered":"https:\/\/www.costaricaguides.com\/tortuguero-hotels-packages-form\/"},"modified":"2020-03-06T17:35:36","modified_gmt":"2020-03-06T17:35:36","slug":"formulario-de-paquetes-de-hoteles-en-tortuguero","status":"publish","type":"page","link":"https:\/\/www.costaricaguides.com\/es\/formulario-de-paquetes-de-hoteles-en-tortuguero\/","title":{"rendered":"Formulario de Paquetes de Hoteles en Tortuguero"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<div role=\"form\" class=\"wpcf7\" id=\"wpcf7-f12167-o1\" lang=\"en-US\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><\/div>\n<form action=\"\/es\/wp-json\/wp\/v2\/pages\/12169#wpcf7-f12167-o1\" method=\"post\" class=\"wpcf7-form\" novalidate=\"novalidate\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"12167\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.0.1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f12167-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<\/div>\n<div id=\"hotels_packages_form_co\" class=\"coral-container\">\n<div style=\"margin-bottom:20px;\" class=\"row\">\n<div style=\"margin-bottom:20px;\" id=\"name-co\" class=\"col-lg-6 col-md-6 col-sm-6 col-xs-12\"><label> Nombre (requerido) <\/label>  <span class=\"wpcf7-form-control-wrap your-name\"><input type=\"text\" name=\"your-name\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span>  <\/div>\n<div id=\"last-co\" class=\"col-lg-6 col-md-6 col-sm-6 col-xs-12\"><label> Apellidos (requerido) <\/label>  <span class=\"wpcf7-form-control-wrap last-name\"><input type=\"text\" name=\"last-name\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span>  <\/div><\/div>\n<div style=\"margin-bottom:20px;\" class=\"row\">\n<div style=\"margin-bottom:20px;\" id=\"mail-co\" class=\"col-lg-6 col-md-6 col-sm-6 col-xs-12\"><label> Email (requerido) <\/label>  <span class=\"wpcf7-form-control-wrap your-email\"><input type=\"email\" name=\"your-email\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-email wpcf7-validates-as-required wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/div>\n<div id=\"phone-co\" class=\"col-lg-6 col-md-6 col-sm-6 col-xs-12\"><label> Tel&eacute;fono <\/label>  <span class=\"wpcf7-form-control-wrap phone\"><input type=\"tel\" name=\"phone\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-tel wpcf7-validates-as-tel\" aria-invalid=\"false\" \/><\/span> <\/div><\/div>\n<div style=\"margin-bottom:20px;\" class=\"row\">\n<div style=\"margin-bottom:20px;\" id=\"pick-co\" class=\"col-lg-6 col-md-6 col-sm-6 col-xs-12\"><label> Recoger (requerido) <\/label>  <span class=\"wpcf7-form-control-wrap pick-up\"><input type=\"text\" name=\"pick-up\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/div>\n<div id=\"drop-co\" class=\"col-lg-6 col-md-6 col-sm-6 col-xs-12\"><label> Dejar (requerido) <\/label>  <span class=\"wpcf7-form-control-wrap drop-off\"><input type=\"text\" name=\"drop-off\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/div><\/div>\n<div style=\"margin-bottom:20px;\" class=\"row\">\n<div style=\"margin-bottom:20px;\" id=\"arrival-co\" class=\"col-lg-6 col-md-6 col-sm-6 col-xs-12\"><label> Fecha de LLegada (requerido) <\/label>  <span class=\"wpcf7-form-control-wrap arrival-date\"><input type=\"date\" name=\"arrival-date\" value=\"\" class=\"wpcf7-form-control wpcf7-date wpcf7-validates-as-required wpcf7-validates-as-date\" min=\"2026-05-13\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/div>\n<div id=\"adults-co\" class=\"col-lg-6 col-md-6 col-sm-6 col-xs-12\"><label> Cantidad de Adultos (requerido) <\/label>  <span class=\"wpcf7-form-control-wrap adults\"><input type=\"number\" name=\"adults\" value=\"2\" class=\"wpcf7-form-control wpcf7-number wpcf7-validates-as-required wpcf7-validates-as-number\" min=\"1\" max=\"100\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/div><\/div>\n<div style=\"margin-bottom:20px;\" class=\"row\">\n<div style=\"margin-bottom:20px;\" id=\"package-co\" class=\"col-lg-6 col-md-6 col-sm-6 col-xs-12\"><label> Paquete (requerido) <\/label>  <span class=\"wpcf7-form-control-wrap package\"><select name=\"package\" class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\"><option value=\"\">---<\/option><option value=\"2 Days \/ 1 Night opt 1\">2 Days \/ 1 Night opt 1<\/option><option value=\"3 Days \/ 2 Nights\">3 Days \/ 2 Nights<\/option><option value=\"2 Days \/ 1 Night opt 2\">2 Days \/ 1 Night opt 2<\/option><\/select><\/span> <\/div>\n<div id=\"hotel-co\" class=\"col-lg-6 col-md-6 col-sm-6 col-xs-12\"><label> Hotel (requerido) <\/label>  <span class=\"wpcf7-form-control-wrap hotel\"><select name=\"hotel\" class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\"><option value=\"\">---<\/option><option value=\"Laguna Lodge\">Laguna Lodge<\/option><option value=\"Hotel Mawamba\">Hotel Mawamba<\/option><option value=\"Pachira Lodge\">Pachira Lodge<\/option><\/select><\/span> <\/div><\/div>\n<div style=\"margin-bottom:20px;\" class=\"row\">\n<div style=\"margin-bottom:20px;\" id=\"comments-co\" class=\"col-lg-12 col-md-12 col-sm-12 col-xs-12\"><label> Comentarios <\/label>  <span class=\"wpcf7-form-control-wrap your-message\"><textarea name=\"your-message\" cols=\"40\" rows=\"10\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\"><\/textarea><\/span> <\/div><\/div>\n<div style=\"margin-bottom:20px;\" class=\"row\">\n<div id=\"btn-co\" class=\"col-lg-12 col-md-12 col-sm-12 col-xs-12\"> <input type=\"submit\" value=\"Enviar\" class=\"wpcf7-form-control wpcf7-submit\" \/> <\/div><\/div>\n<\/div>\n<div class=\"wpcf7-response-output wpcf7-display-none\"><\/div><\/form><\/div>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text][\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":13,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/template-with-right-sidebar.php","meta":{"_joinchat":[],"footnotes":""},"class_list":["post-12169","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.costaricaguides.com\/es\/wp-json\/wp\/v2\/pages\/12169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.costaricaguides.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.costaricaguides.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.costaricaguides.com\/es\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.costaricaguides.com\/es\/wp-json\/wp\/v2\/comments?post=12169"}],"version-history":[{"count":2,"href":"https:\/\/www.costaricaguides.com\/es\/wp-json\/wp\/v2\/pages\/12169\/revisions"}],"predecessor-version":[{"id":12170,"href":"https:\/\/www.costaricaguides.com\/es\/wp-json\/wp\/v2\/pages\/12169\/revisions\/12170"}],"wp:attachment":[{"href":"https:\/\/www.costaricaguides.com\/es\/wp-json\/wp\/v2\/media?parent=12169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}